{"id":168,"count":7,"description":"","link":"https:\/\/gaesolution.es\/en\/categorias-gas\/cocina-agua-caliente-y-calefaccion\/","name":"Cocina, Agua Caliente y Calefacci\u00f3n","slug":"cocina-agua-caliente-y-calefaccion","taxonomy":"categorias-gas","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/gaesolution.es\/en\/wp-json\/wp\/v2\/categorias-gas\/168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gaesolution.es\/en\/wp-json\/wp\/v2\/categorias-gas"}],"about":[{"href":"https:\/\/gaesolution.es\/en\/wp-json\/wp\/v2\/taxonomies\/categorias-gas"}],"wp:post_type":[{"href":"https:\/\/gaesolution.es\/en\/wp-json\/wp\/v2\/tarifas-gas?categorias-gas=168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}